{"id":1966,"date":"2020-10-01T18:11:10","date_gmt":"2020-10-01T23:11:10","guid":{"rendered":"https:\/\/worldjusticeproject.mx\/?p=1966"},"modified":"2020-10-01T18:19:02","modified_gmt":"2020-10-01T23:19:02","slug":"prision-preventiva-oficiosa-a-la-mesa","status":"publish","type":"post","link":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/","title":{"rendered":"Prisi\u00f3n preventiva oficiosa a la mesa"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1966\" class=\"elementor elementor-1966\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34a7466 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34a7466\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bfa585\" data-id=\"3bfa585\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fae0f52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fae0f52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea9f8fd\" data-id=\"ea9f8fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7b32be elementor-widget elementor-widget-text-editor\" data-id=\"e7b32be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Por: Marien Rivera<\/h5><h3><strong><span style=\"font-size: 12pt;\">Entrada: detenci\u00f3n<\/span><\/strong><\/h3><p><span style=\"font-size: 12pt;\">Son casi las nueve de la noche de un jueves y vas caminando hacia la tiendita que queda cerca de tu casa. Fue un d\u00eda pesado en el trabajo y se te antoj\u00f3 una cerveza. Llevas puesto tu cubrebocas, unos tenis, pantalones de mezclilla y una vieja sudadera roja, de esas que tienen una bolsa grande para guardar las manos y una capucha detr\u00e1s. Sin detenerte, revisas las bolsas del pantal\u00f3n para asegurarte de que llevas dinero suficiente. Alguien pasa corriendo y golpea tu codo. Billetes y monedas caen al piso. Le gritas al responsable pero no voltea. Tan pronto como terminas de levantar el \u00faltimo peso, una patrulla se detiene al lado de ti. Te meten a la fuerza al veh\u00edculo. Ah\u00ed te explican que reci\u00e9n acaban de asaltar una casa de la colonia. La empleada del hogar, a\u00fan muy alterada, asegur\u00f3 que era imposible saber si era una mujer o un hombre, pero que se trataba de alguien de estatura media, que vest\u00eda una sudadera roja, jeans holgados y calzado deportivo. Justo igual que t\u00fa. La testigo solo mencion\u00f3 que un pedazo de tela cubr\u00eda pr\u00e1cticamente toda la cara del ladr\u00f3n. Ante tus desesperadas aclaraciones, la polic\u00eda te dice que da lo mismo lo que les digas, te vieron correr y te persiguen desde hace cinco cuadras.<\/span><\/p><h3><strong><span style=\"font-size: 12pt;\">Segundo tiempo: puesta a disposici\u00f3n<\/span><\/strong><\/h3><p><span style=\"font-size: 12pt;\">Media hora despu\u00e9s ya est\u00e1s en la agencia del ministerio p\u00fablico. No entiendes nada. Te tienen esperando de pie, con las manos esposadas y viendo hacia la pared. Todo lo que llevabas contigo ahora son\u00a0<em>indicios en resguardo<\/em>. Pasan un par de horas, quiz\u00e1 m\u00e1s. Finalmente, el polic\u00eda entrega al fiscal en turno un informe que termin\u00f3 de llenar unos minutos antes. Conversan. El fiscal le confirma que tiene todo lo que necesita para ratificar la detenci\u00f3n: evidencia de que un delito se cometi\u00f3, una persona sospechosa detenida en plena huida y la identificaci\u00f3n ocular de la denunciante. Es un caso f\u00e1cil que har\u00e1 quedar bien a todos los involucrados. Te internar\u00e1n uno o dos d\u00edas en una de las celdas improvisadas de la agencia llenas de humedad, goteras y olor a drenaje. Entre el bullicio escuchas que, a partir de ese momento, corren las 48 horas que tiene el fiscal para armar el argumento con el que convencer\u00e1 al juez de iniciar un proceso penal en tu contra.<\/span><\/p><h3><strong><span style=\"font-size: 12pt;\">Plato fuerte: prisi\u00f3n preventiva oficiosa<\/span><\/strong><\/h3><p><span style=\"font-size: 12pt;\">Llegan el d\u00eda y la hora de tu audiencia. El juez aparece. Lee mec\u00e1nicamente una lista de derechos, te explica lo que va a pasar a continuaci\u00f3n y te pregunta si entendiste. Lo que est\u00e1 sucediendo a tu alrededor te confunde e intimida, as\u00ed que respondes que s\u00ed, aunque no sea cierto. Como no tienes abogado particular, el juez te asigna en ese momento un defensor p\u00fablico. \u00bfC\u00f3mo podr\u00e1 defenderte alguien que acabas de conocer? El licenciado Ju\u00e1rez, defensor p\u00fablico, se sienta a tu lado; se ve tan aturdido y desorientado como t\u00fa. Te dice que todo va a estar bien, que tiene experiencia. Creerle parece imposible.<\/span><\/p><p><span style=\"font-size: 12pt;\">El juez le da la palabra al fiscal. Te concentras para poner atenci\u00f3n. El fiscal repite la versi\u00f3n de los hechos que ya te hab\u00eda adelantado la polic\u00eda el d\u00eda de tu arresto, pero hay informaci\u00f3n que no hab\u00edas escuchado antes. El fiscal a\u00f1ade que la empleada dom\u00e9stica, denunciante y testigo en tu caso, asegur\u00f3 haberte reconocido pues, con mucha frecuencia, te ha visto pasar por la casa en la que trabaja. Es evidente, dice la parte acusadora, que esas iteraciones indican trabajo de \u201cinteligencia criminal\u201d. Volteas a ver a tu defensor, \u00e9l no se inmuta. No sabe que la casa robada est\u00e1 en tu trayecto al trabajo, al pan, a las tortillas, a la lavander\u00eda, al supermercado. La vivienda en cuesti\u00f3n est\u00e1 en la calle por la que caminas todos los d\u00edas por lo menos una vez, de ida y vuelta. El fiscal, con tono solemne, te imputa haber cometido un robo a casa habitaci\u00f3n. El juez pregunta si la defensa tiene algo que decir. Ju\u00e1rez no solo no reacciona a ese est\u00edmulo, te dice en voz baja que es mejor no pelear en ese momento. Entonces el juez te pregunta si quieres 72 horas para defenderte. Si decides no tomar esas horas, \u00e9l decidir\u00e1 en ese mismo momento sobre la validez de la imputaci\u00f3n. Lo piensas por unos minutos. Ju\u00e1rez balbucea cosas que no entiendes. Resuelves que no tiene ning\u00fan caso alargar esta agon\u00eda. Quieres saber qu\u00e9 pasar\u00e1 contigo.<\/span><\/p><p><span style=\"font-size: 12pt;\">Entre las cosas que el defensor debi\u00f3 advertirte \u2013pero omiti\u00f3\u2013 est\u00e1 el nada min\u00fasculo detalle de que el poder legislativo acaba de incluir el robo a casa habitaci\u00f3n al infame cat\u00e1logo de delitos de \u201cprisi\u00f3n preventiva oficiosa\u201d. D\u00edas antes de esta pesadilla, escuchaste a tu pap\u00e1 aplaudir la ampliaci\u00f3n de delitos para los que esa medida se receta de manera autom\u00e1tica: \u201cya no se nos van a escapar los delincuentes por tecnicismos insignificantes\u201d. Pero ni en ese momento, ni mucho menos ahora, sabes qu\u00e9 es la prisi\u00f3n preventiva ni qu\u00e9 implica ese adjetivo que le confiere\u00a0<em>oficiosidad<\/em>.<\/span><\/p><p><span style=\"font-size: 12pt;\">Te habr\u00eda sido \u00fatil saber que la prisi\u00f3n preventiva es una precauci\u00f3n que se usa para asegurar que una persona se\u00f1alada como responsable de cometer un delito no se escapar\u00e1 y estar\u00e1 presente en su proceso penal. Entre que son peras o son manzanas, \u00bfte vas a la c\u00e1rcel aunque las autoridades a\u00fan no tengan idea de si cometiste el delito o no? Exacto.<\/span><\/p><p><span style=\"font-size: 12pt;\">Por supuesto, existen otras formas menos dr\u00e1sticas de asegurar que una persona se presente a sus audiencias. La prisi\u00f3n preventiva y todas las otras medidas cautelares se ordenan despu\u00e9s de un an\u00e1lisis de riesgos: \u00bfhuir\u00e1s del pa\u00eds o podr\u00e1n juzgarte sin temor a que no te presentes a audiencia? A Emilio Lozoya le dieron un brazalete electr\u00f3nico, por ejemplo, y los abogados de Elba Esther Gordillo le consiguieron un arraigo domiciliario. La cosa es que, cuando un delito se suma a la lista de prisi\u00f3n preventiva\u00a0<em>oficiosa<\/em>, la discusi\u00f3n sobre si hay un riesgo real de que te escapes no ocurre. Basta con que se valore que exista una posibilidad de que hayas cometido el delito para que se te env\u00ede autom\u00e1ticamente a prisi\u00f3n. Ese es tu caso.<\/span><\/p><p><span style=\"font-size: 12pt;\">Ya en la parte final de tu audiencia, el juez anuncia que la fiscal\u00eda tendr\u00e1 seis meses para completar su investigaci\u00f3n y despu\u00e9s deber\u00e1 formular su acusaci\u00f3n. Esta es la parte que m\u00e1s trabajo te cuesta entender: \u00bfpor qu\u00e9 necesitar\u00edan tanto tiempo de investigaci\u00f3n para luego acusarte de cometer un delito por el que ya llevar\u00e1s medio a\u00f1o en la c\u00e1rcel?<\/span><\/p><h3><strong><span style=\"font-size: 12pt;\">Postre: acusaci\u00f3n<\/span><\/strong><\/h3><p><span style=\"font-size: 12pt;\">Llevas dos meses en el penal de San Mateo. Tus padres vendieron tu coche y todo lo que encontraron de valor en tu casa para contratarte un abogado privado. Meses antes, ambos perdieron su empleo por culpa de la pandemia. El nuevo abogado te dice que sucedi\u00f3 algo que podr\u00eda jugar a tu favor. La casa por la que te acusaron hab\u00eda sido robada nuevamente. Esta vez se\u00f1alaron a Rosa, la empleada dom\u00e9stica que fue testigo y denunciante en tu proceso. Era demasiada casualidad que robaran la misma vivienda dos veces, que supieran perfectamente d\u00f3nde hab\u00eda art\u00edculos de valor, o cu\u00e1ndo entrar para que los due\u00f1os no estuvieran presentes. Si la acusan a ella por los dos robos, explica tu abogado, tendr\u00e1n que dejarte en libertad. Te suena demasiado f\u00e1cil para ser verdad.<\/span><\/p><p><span style=\"font-size: 12pt;\">Medio a\u00f1o despu\u00e9s llega el d\u00eda de tu audiencia intermedia, cuando por fin la fiscal\u00eda te acusar\u00e1. Tras algunas formalidades, el fiscal empieza a desarrollar su teor\u00eda del caso. Por algunos segundos, sientes un alivio enorme cuando escuchas al fiscal mencionar el nombre de Rosa. Quiz\u00e1 se aclarar\u00e1 todo. Pero la hip\u00f3tesis que presenta la parte acusadora plantea un escenario a\u00fan m\u00e1s complicado: Rosa y t\u00fa forman parte de una banda de delincuentes dedicada al robo de casa habitaci\u00f3n que opera en la delegaci\u00f3n Miguel Hidalgo. Al d\u00eda siguiente, la jefa de Gobierno presume la desarticulaci\u00f3n de una de las organizaciones criminales m\u00e1s peligrosas de la ciudad.<\/span><\/p><h3><strong><span style=\"font-size: 12pt;\">Sobremesa: impunidad<\/span><\/strong><\/h3><p><span style=\"font-size: 12pt;\">La figura mexicana de la prisi\u00f3n preventiva<em>\u00a0oficiosa<\/em>\u00a0ha tenido efectos devastadores para la seguridad p\u00fablica en el pa\u00eds. Atr\u00e1s de ese invento hay dos falacias principales: primero, que los jueces corruptos dejan libres a los delincuentes en cuanto tienen oportunidad y, segundo, que es mejor encarcelar a los \u201cdelincuentes\u201d, aunque sea por unos meses, en vez de que sigan cometiendo delitos con toda libertad. La conclusi\u00f3n es que, mientras m\u00e1s delitos ingresen en la lista de prisi\u00f3n preventiva <em>oficiosa<\/em>, menos margen de actuaci\u00f3n tendr\u00e1n los jueces y, por lo tanto, m\u00e1s delincuentes se quedar\u00e1n inhabilitados en la c\u00e1rcel. Pocas cosas podr\u00edan estar m\u00e1s alejadas de la realidad.<\/span><\/p><p><span style=\"font-size: 12pt;\">Mientras m\u00e1s baja est\u00e9 la vara para que un fiscal logre enviar a prisi\u00f3n a una persona acusada de un delito, el imperativo de realizar una investigaci\u00f3n objetiva y seria se vuelve un costo innecesario. Si la investigaci\u00f3n es de mala calidad o de plano nula pero suficiente para vincular a una persona a proceso, la probabilidad de que muchas m\u00e1s personas inocentes terminen en la c\u00e1rcel aumenta. Y, por si no fuera suficiente, hay otra consecuencia igual de grave y evidente: si las fiscal\u00edas invierten su tiempo y recursos en armar carpetas con oficios y acusar a personas que no participaron en ning\u00fan delito, entonces van a pasar meses o a\u00f1os antes de que choquen con la realidad de que nadie nunca investig\u00f3 a quienes s\u00ed los cometieron. Para entonces ya habr\u00e1 sido demasiado tarde. La prisi\u00f3n preventiva <em>oficiosa<\/em> inhibe la profesionalizaci\u00f3n de la investigaci\u00f3n criminal y perpet\u00faa un sistema que encarcela, pero no disminuye la impunidad; m\u00e1s a\u00fan, la alimenta con personas inocentes. La iron\u00eda es brutal.\u00a0<\/span><\/p><p>\u00a0<\/p><p><em>Este texto fue publicado originalmente en la revista <strong>Letras Libres<\/strong>, edici\u00f3n octubre 2020.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Entrada: detenci\u00f3n Son casi las nueve de la noche de un jueves y vas caminando hacia la tiendita que queda cerca de tu casa. Fue un d\u00eda pesado en el trabajo y se te antoj\u00f3 una cerveza. Llevas puesto tu cubrebocas, unos tenis, pantalones de mezclilla y una vieja sudadera roja, de esas que tienen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[137,107,136],"class_list":["post-1966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-detencion","tag-ministerio-publico","tag-prision-preventiva-oficiosa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)\" \/>\n<meta property=\"og:description\" content=\"Entrada: detenci\u00f3n Son casi las nueve de la noche de un jueves y vas caminando hacia la tiendita que queda cerca de tu casa. Fue un d\u00eda pesado en el trabajo y se te antoj\u00f3 una cerveza. Llevas puesto tu cubrebocas, unos tenis, pantalones de mezclilla y una vieja sudadera roja, de esas que tienen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/\" \/>\n<meta property=\"og:site_name\" content=\"World Justice Project (M\u00e9xico)\" \/>\n<meta property=\"article:author\" content=\"http:\/\/facebook.com\/thewjp\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-01T23:11:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-01T23:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"World Justice Project (M\u00e9xico)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/thewjp_mx\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Justice Project (M\u00e9xico)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/\"},\"author\":{\"name\":\"World Justice Project (M\u00e9xico)\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/#\\\/schema\\\/person\\\/d0e3a283fc3feefe1055612e257c7d46\"},\"headline\":\"Prisi\u00f3n preventiva oficiosa a la mesa\",\"datePublished\":\"2020-10-01T23:11:10+00:00\",\"dateModified\":\"2020-10-01T23:19:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/\"},\"wordCount\":1772,\"image\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldjusticeproject.mx\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Imagen-de-iOS-1.jpg\",\"keywords\":[\"detenci\u00f3n\",\"ministerio publico\",\"prisi\u00f3n preventiva oficiosa\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/\",\"url\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/\",\"name\":\"Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldjusticeproject.mx\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Imagen-de-iOS-1.jpg\",\"datePublished\":\"2020-10-01T23:11:10+00:00\",\"dateModified\":\"2020-10-01T23:19:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/#\\\/schema\\\/person\\\/d0e3a283fc3feefe1055612e257c7d46\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldjusticeproject.mx\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Imagen-de-iOS-1.jpg\",\"contentUrl\":\"https:\\\/\\\/worldjusticeproject.mx\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Imagen-de-iOS-1.jpg\",\"width\":2560,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/prision-preventiva-oficiosa-a-la-mesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/worldjusticeproject.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prisi\u00f3n preventiva oficiosa a la mesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/#website\",\"url\":\"https:\\\/\\\/worldjusticeproject.mx\\\/\",\"name\":\"World Justice Project (M\u00e9xico)\",\"description\":\"Sitio web de la oficina en M\u00e9xico de la organizaci\u00f3n basada en Washington DC, Estados Unidos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldjusticeproject.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldjusticeproject.mx\\\/#\\\/schema\\\/person\\\/d0e3a283fc3feefe1055612e257c7d46\",\"name\":\"World Justice Project (M\u00e9xico)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"World Justice Project (M\u00e9xico)\"},\"description\":\"Staff Editorial de World Justice Project M\u00e9xico\",\"sameAs\":[\"http:\\\/\\\/worldjusticeproject.mx\",\"http:\\\/\\\/facebook.com\\\/thewjp\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/twitter.com\\\/thewjp_mx\"],\"url\":\"https:\\\/\\\/worldjusticeproject.mx\\\/en\\\/author\\\/newemage\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/","og_locale":"en_US","og_type":"article","og_title":"Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)","og_description":"Entrada: detenci\u00f3n Son casi las nueve de la noche de un jueves y vas caminando hacia la tiendita que queda cerca de tu casa. Fue un d\u00eda pesado en el trabajo y se te antoj\u00f3 una cerveza. Llevas puesto tu cubrebocas, unos tenis, pantalones de mezclilla y una vieja sudadera roja, de esas que tienen [&hellip;]","og_url":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/","og_site_name":"World Justice Project (M\u00e9xico)","article_author":"http:\/\/facebook.com\/thewjp","article_published_time":"2020-10-01T23:11:10+00:00","article_modified_time":"2020-10-01T23:19:02+00:00","og_image":[{"width":2560,"height":1400,"url":"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg","type":"image\/jpeg"}],"author":"World Justice Project (M\u00e9xico)","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/thewjp_mx","twitter_misc":{"Written by":"World Justice Project (M\u00e9xico)","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#article","isPartOf":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/"},"author":{"name":"World Justice Project (M\u00e9xico)","@id":"https:\/\/worldjusticeproject.mx\/#\/schema\/person\/d0e3a283fc3feefe1055612e257c7d46"},"headline":"Prisi\u00f3n preventiva oficiosa a la mesa","datePublished":"2020-10-01T23:11:10+00:00","dateModified":"2020-10-01T23:19:02+00:00","mainEntityOfPage":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/"},"wordCount":1772,"image":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#primaryimage"},"thumbnailUrl":"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg","keywords":["detenci\u00f3n","ministerio publico","prisi\u00f3n preventiva oficiosa"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/","url":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/","name":"Prisi\u00f3n preventiva oficiosa a la mesa - World Justice Project (M\u00e9xico)","isPartOf":{"@id":"https:\/\/worldjusticeproject.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#primaryimage"},"image":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#primaryimage"},"thumbnailUrl":"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg","datePublished":"2020-10-01T23:11:10+00:00","dateModified":"2020-10-01T23:19:02+00:00","author":{"@id":"https:\/\/worldjusticeproject.mx\/#\/schema\/person\/d0e3a283fc3feefe1055612e257c7d46"},"breadcrumb":{"@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#primaryimage","url":"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg","contentUrl":"https:\/\/worldjusticeproject.mx\/wp-content\/uploads\/2020\/10\/Imagen-de-iOS-1.jpg","width":2560,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/worldjusticeproject.mx\/en\/prision-preventiva-oficiosa-a-la-mesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/worldjusticeproject.mx\/"},{"@type":"ListItem","position":2,"name":"Prisi\u00f3n preventiva oficiosa a la mesa"}]},{"@type":"WebSite","@id":"https:\/\/worldjusticeproject.mx\/#website","url":"https:\/\/worldjusticeproject.mx\/","name":"World Justice Project (M\u00e9xico)","description":"Sitio web de la oficina en M\u00e9xico de la organizaci\u00f3n basada en Washington DC, Estados Unidos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldjusticeproject.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/worldjusticeproject.mx\/#\/schema\/person\/d0e3a283fc3feefe1055612e257c7d46","name":"World Justice Project (M\u00e9xico)","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6531cff9e750e0a8f2e11dce1356c7675b1506f572d4663cd12ca5d739dc663f?s=96&d=wp_user_avatar&r=g","caption":"World Justice Project (M\u00e9xico)"},"description":"Staff Editorial de World Justice Project M\u00e9xico","sameAs":["http:\/\/worldjusticeproject.mx","http:\/\/facebook.com\/thewjp","https:\/\/x.com\/http:\/\/twitter.com\/thewjp_mx"],"url":"https:\/\/worldjusticeproject.mx\/en\/author\/newemage\/"}]}},"_links":{"self":[{"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/posts\/1966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/comments?post=1966"}],"version-history":[{"count":5,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/posts\/1966\/revisions"}],"predecessor-version":[{"id":1977,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/posts\/1966\/revisions\/1977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/media\/1969"}],"wp:attachment":[{"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/media?parent=1966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/categories?post=1966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldjusticeproject.mx\/en\/wp-json\/wp\/v2\/tags?post=1966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}